{"id":17735,"date":"2022-08-12T09:36:20","date_gmt":"2022-08-12T09:36:20","guid":{"rendered":"https:\/\/www.criteo.com\/es\/?page_id=17735"},"modified":"2024-04-03T15:48:29","modified_gmt":"2024-04-03T15:48:29","slug":"ultimate-guide-commerce-media","status":"publish","type":"page","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/","title":{"rendered":"The Ultimate Guide to Commerce Media"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":18,"featured_media":17736,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/ugcm.php","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[544],"class_list":["post-17735","page","type-page","status-publish","has-post-thumbnail"],"acf":{"stae_popup_enable":false,"track_page_in_segment":false,"segment_page_name":"","header_video_poster":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ugcm-header-bg-1.jpg","header_video_file":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Main_header_ES.mp4","intro":"<h3>La necesidad es la madre de los inventos.<\/h3>\n<p>Las grandes ideas surgen de momentos de necesidad de solucionar algo que no funciona o de crear algo nuevo cuando hay un vac\u00edo en el momento actual.<\/p>\n<p>Esta es la historia original de los Commerce Media.<\/p>\n<p>Tratando de responder a las peticiones de los consumidores en temas de privacidad, el sector de la publicidad digital est\u00e1 inmerso en un verdadero proceso de transformaci\u00f3n. Es un cambio positivo que pone a los consumidores en el centro del ecosistema de la publicidad, pero tambi\u00e9n un cambio dif\u00edcil que ha planteado m\u00e1s preguntas que respuestas. En medio de todas las discusiones sobre cu\u00e1l ser\u00e1 el futuro de una publicidad segmentada responsable, los Commerce Media han surgido como una posible soluci\u00f3n.<\/p>\n<p>Los Commerce Media ofrecen a los Profesionales del Marketing y a los propietarios de medios lo que necesitan: una manera sencilla y segura de impulsar el crecimiento a trav\u00e9s de la publicidad.<\/p>\n<p>Le da a los consumidores lo que quieren (anuncios relevantes, seg\u00fan sus criterios).<\/p>\n<p>Y contribuye a que el Internet abierto siga mejorando (porque es donde se dan el descubrimiento, la innovaci\u00f3n y la capacidad de elecci\u00f3n).<\/p>\n<p>En resumidas cuentas, los Commerce Media es algo muy grande que est\u00e1 a la vuelta de la esquina, lo que significa que es un buen momento para familiarizarse con ellos ahora. En esta gu\u00eda, descubre exactamente lo que son los Commerce Media, por qu\u00e9 est\u00e1n en tendencia y c\u00f3mo solucionan las necesidades m\u00e1s apremiantes del sector.<\/p>\n","sections":[{"section_title":"\u00bfQu\u00e9 son los Commerce Media?","section_anchor":"what-is-commerce-media","optional_section_classes":"","section_header_background_type":"image","section_header_background":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header-1-SPANISH-scaled.jpg","section_header_background_video":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header_1_notext.mp4","section_header_title_img":false,"section_body":{"content_area":[{"white_bg":true,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<p><strong>Definici\u00f3n:<\/strong> Los Commerce Media permiten tanto a los anunciantes de retail como a los que no lo son (p.ej. sectores de Reparto de comidas y Viajes) a conectar con las audiencias a lo largo de su proceso de compra en retailers y publishers del Internet abierto, sacando el m\u00e1ximo partido de datos comerciales para mejorar experiencias y vincular la inversi\u00f3n en publicidad directamente con los resultados obtenidos.<\/p>\n"}]},{"white_bg":false,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>Para simplificar, los Commerce Media conectan a los Profesionales del Marketing y a los propietarios de medios con datos propios y entre s\u00ed para que todos puedan ofrecer mejores experiencias a los consumidores a la vez que garantizar una medici\u00f3n de resultados precisa.<\/p>\n<p>Si lo miramos de otra manera, los Commerce Media re\u00fanen la publicidad program\u00e1tica y el Retail Media y ampl\u00edan el campo para incluir a negocios que no son de retail, todo ello en el Internet abierto, donde el control est\u00e1 en manos de los Profesionales del Marketing y los propietarios de medios.<\/p>\n"},{"acf_fc_layout":"media_slider","one_image_slider":true,"example_slider":false,"media_type":"image","single_image":{"ID":17828,"id":17828,"title":"ch1-a copy","filename":"ch1-a-copy.png","filesize":32252,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy.png","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/ch1-a-copy\/","alt":"","author":"55","description":"","caption":"","name":"ch1-a-copy","status":"inherit","uploaded_to":17735,"date":"2022-08-22 17:18:40","modified":"2022-08-22 17:18:40","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":351,"height":310,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy-300x265.png","medium-width":300,"medium-height":265,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy.png","medium_large-width":351,"medium_large-height":310,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy.png","large-width":351,"large-height":310,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy.png","1536x1536-width":351,"1536x1536-height":310,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy.png","2048x2048-width":351,"2048x2048-height":310,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy.png","success-story-width":351,"success-story-height":310,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy-24x24.png","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy-48x48.png","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy-96x96.png","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy-150x150.png","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-a-copy-300x300.png","profile_300-width":300,"profile_300-height":300}},"single_wistia_video_id":"4rwpabnq9c","slides":[{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"PRINCIPALES PUNTOS \u2013 N\u00ba. 1","subtitle":"Una soluci\u00f3n basada en datos propios","description":"<p>Ofrece acceso a una amplia base de datos propios seguros para la privacidad que pueden aprovecharse de diferentes maneras.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"PRINCIPALES PUNTOS \u2013 N\u00ba. 2","subtitle":"Abierta","description":"<p>Conecta a los Profesionales del Marketing y a los propietarios de medios en el Internet abierto, donde tiene lugar el descubrimiento, la innovaci\u00f3n y la elecci\u00f3n.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"PRINCIPALES PUNTOS \u2013 N\u00ba. 3","subtitle":"Inteligente","description":"<p>Utiliza datos comerciales a gran escala (datos de compra e intenci\u00f3n de compra) que se aplican a trav\u00e9s de la Inteligencia Artificial (IA) construida para el comercio para:<\/p>\n<ul>\n<li>Obtener insights sobre audiencias<\/li>\n<li>Mejorar la segmentaci\u00f3n online<\/li>\n<li>Ofrecer experiencias relevantes<\/li>\n<li>Conectar la actividad online con los resultados online y en tienda f\u00edsica<\/li>\n<\/ul>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"PRINCIPALES PUNTOS \u2013 N\u00ba. 4","subtitle":"Full-funnel","description":"<p>Capta la atenci\u00f3n de las audiencias en todas las fases, desde el descubrimiento hasta la consideraci\u00f3n y la conversi\u00f3n, y a lo largo del proceso de adquisici\u00f3n y retenci\u00f3n, mientras que ofrece resultados comerciales medibles en cada una de las fases.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"PRINCIPALES PUNTOS \u2013 N\u00ba. 5","subtitle":"Tambi\u00e9n para los propietarios de medios","description":"<p>Los Commerce Media ofrecen tambi\u00e9n la manera mediante la cual los propietarios de medios (publishers y retailers) pueden enriquecer sus datos e inventario propios y present\u00e1rselos a los anunciantes.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"PRINCIPALES PUNTOS \u2013 N\u00ba. 6","subtitle":"Centrada en la audiencia","description":"<p>Permite a los Profesionales del Marketing dejar de lado un enfoque por canales y crear estrategias de publicidad basadas en audiencias de alto valor en todos los canales, dispositivos y formatos.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"PRINCIPALES PUNTOS \u2013 N\u00ba. 7","subtitle":"M\u00e1s relevante","description":"<p>Los datos a gran escala y la IA mejoran la relevancia de los anuncios, lo que genera mejores experiencias de usuario y mejores resultados.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"PRINCIPALES PUNTOS \u2013 N\u00ba. 8","subtitle":"Medible","description":"<p>Entiende bien todo el impacto de tus acciones digitales y conecta cada campa\u00f1a, incluso aquellas de Awareness y consideraci\u00f3n, para desglosar los KPI online y en tienda f\u00edsica (tales como ventas, leads y visitas).<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"PRINCIPALES PUNTOS \u2013 N\u00ba. 9","subtitle":"Segmentable","description":"<p>Los Profesionales del Marketing y los propietarios de medios pueden conectar sus datos propios para encontrar coincidencias y construir, escalar y activar audiencias segmentables.<\/p>\n"}]},{"acf_fc_layout":"subtitle_with_menu_anchor","subtitle":"\u00bfQu\u00e9 son los datos comerciales?","anchor_id":"what-is-commerce-data","menu_item_label":"\u00bfQu\u00e9 son los datos comerciales?"},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>Un conjunto de datos de compra e intenci\u00f3n de compra, que proporcionan insights sobre los comportamientos y los procesos de compra de los consumidores y que pueden utilizarse para lograr mejores resultados. Incluyen:<\/p>\n<ul>\n<li>Visualizaciones de p\u00e1ginas y productos<\/li>\n<li>Productos a\u00f1adidos al carrito<\/li>\n<li>Productos comprados (online y en tienda f\u00edsica)<\/li>\n<li>Clics en anuncio<\/li>\n<li>Datos contextuales de los publishers, como URLs, categor\u00edas contextuales y palabras clave<\/li>\n<li>Informaci\u00f3n sobre productos, como categor\u00edas, SKU, precios, descripciones<\/li>\n<li>Identificadores tales como emails cifrados, n\u00fameros de tel\u00e9fono cifrados e ID de visitantes (tales como ID aleatorios almacenados en cookies de terceros)<\/li>\n<\/ul>\n"},{"acf_fc_layout":"key_points","points":[{"title":"Cuanto m\u00e1s grande mejor","description":"Cuanto m\u00e1s grande sea el conjunto de datos comerciales, m\u00e1s insights obtendr\u00e1s.  "},{"title":"Lo mejor: los datos propios","description":"Los datos comerciales que se basan en datos propios ser\u00e1n vitales para garantizar una capacidad de segmentaci\u00f3n adecuada y para ofrecer experiencias personalizadas."}]}]},{"white_bg":true,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<h4>\u00bfQu\u00e9 ofrecen los datos comerciales a los Profesionales del Marketing?<\/h4>\n<p>Todos los Profesionales del Marketing y propietarios de medios ya disponen de datos comerciales sobre las interacciones de los clientes en sus propiedades (lo que han mirado, lo que han comprado). Pero un mayor conjunto de datos comerciales puede proporcionar una visi\u00f3n global m\u00e1s completa y mostrar qu\u00e9 m\u00e1s est\u00e1n buscando y comprando los consumidores en el Internet abierto y en tienda f\u00edsica.<\/p>\n<p>Los datos comerciales combinados con la IA <strong>aumentan la eficiencia y la eficacia de la publicidad.<\/strong> Ayudan a los Profesionales del Marketing a:<\/p>\n"},{"acf_fc_layout":"media_slider","one_image_slider":true,"example_slider":true,"media_type":"image","single_image":{"ID":17795,"id":17795,"title":"ch1-b-1","filename":"ch1-b-1-1.png","filesize":11553,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1.png","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/ch1-b-1-2\/","alt":"","author":"18","description":"","caption":"","name":"ch1-b-1-2","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:38:34","modified":"2022-08-12 09:38:34","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":351,"height":310,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1-300x265.png","medium-width":300,"medium-height":265,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1.png","medium_large-width":351,"medium_large-height":310,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1.png","large-width":351,"large-height":310,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1.png","1536x1536-width":351,"1536x1536-height":310,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1.png","2048x2048-width":351,"2048x2048-height":310,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1.png","success-story-width":351,"success-story-height":310,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1-24x24.png","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1-48x48.png","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1-96x96.png","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1-150x150.png","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch1-b-1-1-300x300.png","profile_300-width":300,"profile_300-height":300}},"single_wistia_video_id":"hh3sfgea5b","slides":[{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Ejemplo","subtitle":"Obtener una visi\u00f3n general m\u00e1s amplia de sus audiencias que no pueden proporcionar sus datos propios. Identificando el inter\u00e9s y los patrones de intenci\u00f3n de compra, ayuda a los Profesionales del Marketing a comprender mejor lo que quieren los consumidores, y a predecir lo que tienen probabilidades de comprar a continuaci\u00f3n","description":"<p>Los datos comerciales te permiten encontrar a m\u00e1s personas que puedan estar buscando un sistema de sonido surround premium como el que t\u00fa vendes, identificando a los consumidores que hace poco compraron una TV UHD 4K y un conjunto de muebles de comedor.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Ejemplo","subtitle":"Construir audiencias de personas que est\u00e1n activamente en el mercado para ciertos productos","description":"<p>En lugar de llegar a las personas que les gustan los camiones Ford o a un segmento demogr\u00e1fico que *pudiera* estar interesado en los camiones, llega a las personas cuyas se\u00f1ales de intenci\u00f3n de compra muestran que est\u00e1n en <strong>modo compra<\/strong> de un cami\u00f3n Ford en estos momentos.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"","subtitle":"Descubrir qu\u00e9 productos recomendar, qu\u00e9 creatividad conseguir\u00e1 el mayor engagement y qu\u00e9 puja establecer en funci\u00f3n de la relaci\u00f3n valor-coste de cada impresi\u00f3n","description":"<p>Muestra diferentes configuraciones de anuncio y CPC.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Ejemplo","subtitle":"Hacer crecer tu negocio y atraer a nuevos consumidores a tu marca y a tus productos","description":"<p>Construye audiencias Lookalike a partir de una base de datos comerciales m\u00e1s grande e identifica categor\u00edas contextuales y dominios que llevar\u00e1n m\u00e1s consumidores a tu sitio web.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"","subtitle":"Mide los resultados y optimiza las campa\u00f1as en tiempo real","description":""}]},{"acf_fc_layout":"single_stat","stat":"4 de cada 10","description":"marcas conf\u00edan en los medios para acceder a importantes insights sobre clientes (p.ej. datos propios de partners) a los que no ten\u00edan acceso y para aprovechar dichos insights para ofrecer mensajes y ofertas m\u00e1s relevantes y mejorar los resultados de ventas online y en tienda f\u00edsica<sup>1<\/sup>"},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4>\u00bfQu\u00e9 ofrecen los datos comerciales a los propietarios de medios?<\/h4>\n<p>Los datos comerciales y la IA <strong>ofrecen m\u00e1s ingresos <\/strong>a los propietarios de medios ayud\u00e1ndoles a:<\/p>\n"},{"acf_fc_layout":"media_slider","one_image_slider":true,"example_slider":true,"media_type":"video","single_image":false,"single_wistia_video_id":"kn7qwgtojf","slides":[{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Ejemplo","subtitle":"Enriquecer sus datos propios con m\u00e1s insights para ofrecer m\u00e1s opciones de segmentaci\u00f3n de audiencias a sus anunciantes","description":"<p>Una audiencia de consumidores de CE que gastan en el 30% de los precios m\u00e1s altos en pa\u00edses de todo el mundo.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Ejemplo","subtitle":"Personalizar su propio contenido de valor para usuarios y crear mejores experiencias en tienda f\u00edsica, que hagan volver a los visitantes y aumenten los ingresos","description":"<p>Mostrar productos electr\u00f3nicos de gama alta a esa misma audiencia de CE en la p\u00e1gina de inicio.<\/p>\n"}]},{"acf_fc_layout":"single_stat","stat":"73%","description":"de los propietarios de medios quieren optimizar los resultados obtenidos de los medios para generar Awareness y aumentar los ingresos."},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n"}]},{"white_bg":false,"padded_left":false,"content":[{"acf_fc_layout":"subtitle_with_menu_anchor","subtitle":"\u00bfD\u00f3nde ha ido a parar la \u00abe\u00bb de e-commerce?","anchor_id":"missing-e","menu_item_label":"\u00bfD\u00f3nde ha ido a parar la \u00abe\u00bb de e-commerce?"},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>\u00bfPor qu\u00e9 no hablamos de \u00abecommerce media\u00bb?<\/p>\n<p>\u201cEcommerce\u201d se ha convertido en sin\u00f3nimo de retail online. No obstante, <strong>\u201ccommerce\u201d es m\u00e1s amplio que el retail online e incluso que el retail en general<\/strong>. La RAE define el \u201ccomercio\u201d como \u201cCompraventa o intercambio de bienes <strong>o<\/strong> <strong>servicios<\/strong>\u201d. Los Commerce Media son m\u00e1s amplios que el retail tambi\u00e9n, y pueden utilizarse para negocios que no son de retail, como Clasificados, Viajes y Finanzas.<\/p>\n<p><strong>A continuaci\u00f3n compartimos un ejemplo de c\u00f3mo los Commerce Media pueden funcionar para un agente de viajes que desea aumentar las reservas de viajes en Europa: <\/strong><\/p>\n"}]},{"white_bg":false,"padded_left":true,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<h4><i>Captaci\u00f3n<\/i><\/h4>\n"},{"acf_fc_layout":"ad_example","example":[{"example_type":"container-tv","video":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_video-1.mp4","gif":false,"description":"Llega a personas que est\u00e9n buscando activamente viajes de vacaciones en Europa"},{"example_type":"container-tablet","video":false,"gif":{"ID":17751,"id":17751,"title":"offthegrid_showcaseRM-1","filename":"offthegrid_showcaseRM-1.gif","filesize":2678039,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/offthegrid_showcaserm-1\/","alt":"","author":"18","description":"","caption":"","name":"offthegrid_showcaserm-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:02:13","modified":"2022-08-12 09:02:13","menu_order":0,"mime_type":"image\/gif","type":"image","subtype":"gif","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":304,"height":254,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-150x150.gif","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-300x251.gif","medium-width":300,"medium-height":251,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","medium_large-width":304,"medium_large-height":254,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","large-width":304,"large-height":254,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","1536x1536-width":304,"1536x1536-height":254,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","2048x2048-width":304,"2048x2048-height":254,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","success-story-width":304,"success-story-height":254,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-24x24.gif","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-48x48.gif","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-96x96.gif","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-150x150.gif","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-300x254.gif","profile_300-width":300,"profile_300-height":254}},"description":"Construye una audiencia Lookalike a partir de tus clientes que reservaron viajes en Europa"},{"example_type":"container-mobile","video":false,"gif":{"ID":17752,"id":17752,"title":"offthegrid_store-1","filename":"offthegrid_store-1.gif","filesize":1160119,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1.gif","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/offthegrid_store-1\/","alt":"","author":"18","description":"","caption":"","name":"offthegrid_store-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:02:16","modified":"2022-08-12 09:02:16","menu_order":0,"mime_type":"image\/gif","type":"image","subtype":"gif","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":542,"height":448,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1-150x150.gif","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1-300x248.gif","medium-width":300,"medium-height":248,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1.gif","medium_large-width":542,"medium_large-height":448,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1.gif","large-width":542,"large-height":448,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1.gif","1536x1536-width":542,"1536x1536-height":448,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1.gif","2048x2048-width":542,"2048x2048-height":448,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1.gif","success-story-width":542,"success-story-height":448,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1-24x24.gif","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1-48x48.gif","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1-96x96.gif","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1-150x150.gif","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_store-1-300x300.gif","profile_300-width":300,"profile_300-height":300}},"description":"Llega a personas que est\u00e9n buscando ofertas de viajes"}]},{"acf_fc_layout":"wysiwyg","wysiwyg":"<h4><em>Retenci\u00f3n<\/em><\/h4>\n"},{"acf_fc_layout":"ad_example","example":[{"example_type":"container-mobile","video":false,"gif":{"ID":17753,"id":17753,"title":"offthegrid_Cube-1","filename":"offthegrid_Cube-1.gif","filesize":2069717,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1.gif","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/offthegrid_cube-1\/","alt":"","author":"18","description":"","caption":"","name":"offthegrid_cube-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:02:19","modified":"2022-08-12 09:02:19","menu_order":0,"mime_type":"image\/gif","type":"image","subtype":"gif","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":304,"height":254,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1-150x150.gif","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1-300x251.gif","medium-width":300,"medium-height":251,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1.gif","medium_large-width":304,"medium_large-height":254,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1.gif","large-width":304,"large-height":254,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1.gif","1536x1536-width":304,"1536x1536-height":254,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1.gif","2048x2048-width":304,"2048x2048-height":254,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1.gif","success-story-width":304,"success-story-height":254,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1-24x24.gif","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1-48x48.gif","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1-96x96.gif","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1-150x150.gif","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_Cube-1-300x254.gif","profile_300-width":300,"profile_300-height":254}},"description":"Vuelve a atraer a consumidores que reservaron en el pasado un viaje a Jap\u00f3n con creatividades que les animen a realizar su pr\u00f3xima aventura en Italia"},{"example_type":"container-tablet-1","video":false,"gif":{"ID":17751,"id":17751,"title":"offthegrid_showcaseRM-1","filename":"offthegrid_showcaseRM-1.gif","filesize":2678039,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/offthegrid_showcaserm-1\/","alt":"","author":"18","description":"","caption":"","name":"offthegrid_showcaserm-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:02:13","modified":"2022-08-12 09:02:13","menu_order":0,"mime_type":"image\/gif","type":"image","subtype":"gif","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":304,"height":254,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-150x150.gif","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-300x251.gif","medium-width":300,"medium-height":251,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","medium_large-width":304,"medium_large-height":254,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","large-width":304,"large-height":254,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","1536x1536-width":304,"1536x1536-height":254,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","2048x2048-width":304,"2048x2048-height":254,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1.gif","success-story-width":304,"success-story-height":254,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-24x24.gif","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-48x48.gif","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-96x96.gif","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-150x150.gif","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_showcaseRM-1-300x254.gif","profile_300-width":300,"profile_300-height":254}},"description":"Vuelve a segmentar por los visitantes de tu sitio web que no reservaron vuelos a Europa que hab\u00edan seleccionado previamente"},{"example_type":"container-mobile-full-size","video":false,"gif":{"ID":17755,"id":17755,"title":"offthegrid_lead-1","filename":"offthegrid_lead-1.gif","filesize":4504248,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1.gif","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/offthegrid_lead-1\/","alt":"","author":"18","description":"","caption":"","name":"offthegrid_lead-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:02:27","modified":"2022-08-12 09:02:27","menu_order":0,"mime_type":"image\/gif","type":"image","subtype":"gif","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":304,"height":604,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1-150x150.gif","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1-151x300.gif","medium-width":151,"medium-height":300,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1.gif","medium_large-width":304,"medium_large-height":604,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1.gif","large-width":304,"large-height":604,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1.gif","1536x1536-width":304,"1536x1536-height":604,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1.gif","2048x2048-width":304,"2048x2048-height":604,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1.gif","success-story-width":304,"success-story-height":604,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1-24x24.gif","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1-48x48.gif","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1-96x96.gif","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1-150x150.gif","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/offthegrid_lead-1-300x300.gif","profile_300-width":300,"profile_300-height":300}},"description":"Informa a tus viajeros frecuentes\/ miembros de tu programa de fidelizaci\u00f3n sobre la promoci\u00f3ns"}]},{"acf_fc_layout":"wysiwyg","wysiwyg":"<h4><em>Retail Media<\/em><\/h4>\n<p><em>Dir\u00edgete a aquellos consumidores que buscaron maletas en sitios web de retail con anuncios que incluyan tus paquetes de viajes por Europa.<\/em><\/p>\n<h4><em>Medici\u00f3n<\/em><\/h4>\n<p><em>Conecta la inversi\u00f3n en publicidad directamente con las reservas.<\/em><\/p>\n"}]},{"white_bg":false,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<h4>El comercio no solo sucede online.<\/h4>\n<p>Nuestra encuesta del Shopper Storyrevela que las tiendas f\u00edsicas siguen teniendo hoy en d\u00eda el mismo atractivo que en 2019: Casi 6 de cada 10 consumidores tienen ganas de ir a comprar a las tiendas f\u00edsicas cuando tienen tiempo.<sup>2<\/sup> Adem\u00e1s, lo que empieza online puede acabar en tienda f\u00edsica o vice versa. Y cada vez es m\u00e1s habitual que ambas acciones se produzcan a la vez. Nuestra investigaci\u00f3n puso de manifiesto que m\u00e1s de la mitad de los consumidores realiza compras desde sus tel\u00e9fonos mientras que est\u00e1n en tienda f\u00edsica, ya sea en el sitio web de dicho retailer o de uno de la competencia.<sup>3<\/sup> Los Commerce Media colocan a la audiencia en el centro, facilitando el proceso omnicanal adecuado para ellos, y conectando la inversi\u00f3n en publicidad con los resultados sea donde sea que se generen (online o en tienda f\u00edsica).<\/p>\n"},{"acf_fc_layout":"numbers_block","title":"Lo que ha cambiado es la frecuencia con la que los consumidores compran online mientras est\u00e1n en el interior de una tienda f\u00edsica::","intro_column":[{"uppercase_label":"Click & Ship","number":"51%","description":"realiza compras a trav\u00e9s de su tel\u00e9fono m\u00f3vil en el sitio web de un retailer mientras est\u00e1 en el interior de la tienda f\u00edsica de ese retailer; ha aumentado desde el 38% que lo hac\u00eda en&nbsp;2019."},{"uppercase_label":"Scan & Scram","number":"58%","description":"realiza compras a trav\u00e9s de su tel\u00e9fono m\u00f3vil en otro retailer despu\u00e9s de ver un producto en una tienda f\u00edsica; ha aumentado 1,4 veces, desde el 42% que lo hac\u00eda en 2019."}],"body_subtitle":"\u00bfLas conclusiones?","description":"La mayor\u00eda de los consumidores siguen incluyendo las tiendas f\u00edsicas en su proceso de consideraci\u00f3n, pero la competencia por d\u00f3nde acaban comprando es cada vez m\u00e1s feroz."},{"acf_fc_layout":"wysiwyg","wysiwyg":"<h4>El inventario de Commerce Media est\u00e1 en los publishers en todo el Internet abierto, adem\u00e1s de en retailers y marketplaces.<\/h4>\n<p>Esto despliega todo tipo de oportunidades de adquisici\u00f3n y retenci\u00f3n para todo tipo de negocios. Como, por ejemplo, llegar a nuevos clientes mientras reproducen contenido con <a href=\"https:\/\/www.criteo.com\/es\/solutions\/video-advertising\/\">anuncios de v\u00eddeo<\/a>, influir en ellos mientras leen un art\u00edculo relacionado con <a href=\"https:\/\/www.criteo.com\/es\/products\/contextual-targeting\/\">anuncios contextuales<\/a>, hacer retargeting despu\u00e9s de que hayan visitado tu sitio web o el sitio web de un retailer socio, y volver a atraerlos despu\u00e9s de haberse convertido en clientes.<\/p>\n"},{"acf_fc_layout":"subtitle_with_menu_anchor","subtitle":"Commerce Media, Retail Media, Performance y Brand Marketing, \u00bfen qu\u00e9 se diferencian?","anchor_id":"commerce-online","menu_item_label":"\u00bfEn qu\u00e9 sentido son diferentes?"},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>Los Commerce Media son una nueva categor\u00eda y, a menudo, esto lleva a confusi\u00f3n. Algunas personas utilizan el t\u00e9rmino indistintamente con Retail Media. Otros lo ven como la pr\u00f3xima evoluci\u00f3n del Retail Media. Hay otros que incluso piensan que es como el Performance Marketing, pero con un nombre diferente. Vamos a aclarar los t\u00e9rminos.<\/p>\n<p>Los Commerce Media toman el Retail Media y le dan un sentido m\u00e1s amplio. Incluye una amplia red de publishers del Internet abierto, adem\u00e1s de los retailers. Y permite que los anunciantes que no son de retail y no end\u00e9micos, adem\u00e1s de los anunciantes retail, utilicen datos comerciales e IA (Inteligencia Artificial) para atraer a las audiencias en esos publishers y retailers de manera m\u00e1s eficaz. Tambi\u00e9n incluye una amplia gama de formatos y canales para cumplir los objetivos del Full Funnel, desde v\u00eddeo y CTV hasta anuncios contextuales y de productos patrocinados. Los Commerce Media re\u00fanen todo esto en un \u00fanico lugar.<\/p>\n<p>&nbsp;<\/p>\n\n<table id=\"tablepress-1\" class=\"tablepress tablepress-id-1 tablepress-responsive tablepress-responsive-phone\">\n<thead>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><th class=\"column-2\">Commerce Media<\/th><th class=\"column-3\">Retail Media<\/th><th class=\"column-4\">Performance Marketing<\/th><th class=\"column-5\">Brand Marketing<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><b>Full-funnel<\/b><\/td><td class=\"column-2\"><b>Si.<\/b> <br \/>\nPueden utilizarse para descubrimiento, conversi\u00f3n y retenci\u00f3n.<\/td><td class=\"column-3\"><b>A veces. <\/b><br \/>\nAlgunos proveedores de Retail Media ofrecen una variedad de formatos de display que permiten a las marcas construir Awareness, aumentar las ventas en el punto de compra y hacer retargeting entre las audiencias de retailers.<\/td><td class=\"column-4\"><b>No.<\/b> <br \/>\nPrincipalmente una t\u00e1ctica de Bottom Funnel centrada en impulsar y optimizar para generar conversiones.<\/td><td class=\"column-5\"><b>No.<\/b> <br \/>\nPrincipalmente una t\u00e1ctica de Top Funnel centrada en impulsar el Awareness y optimizar para llegar a los consumidores y generar impresiones.<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\"><b>Datos comerciales propios<\/b><\/td><td class=\"column-2\"><b>Si.<\/b> <br \/>\nLos datos comerciales propios a gran escala son la columna vertebral de los Commerce Media.<\/td><td class=\"column-3\"><b>S\u00ed.<\/b><br \/>\nLa escala de los datos es menor que la de los Commerce Media, ya que no incluyen inputs de sitios web de otros publishers\/ marcas.<\/td><td class=\"column-4\"><b>No.<\/b> <br \/>\nNormalmente utilizan cookies de terceros y datos sobre el comportamiento y carecen de la escala de los datos comerciales que los Commerce Media s\u00ed tienen. Cualquier dato propio utilizado depende mucho de la coincidencia de cookies de terceros.<\/td><td class=\"column-5\"><b>No.<\/b> <br \/>\nNormalmente utilizan cookies de terceros y datos demogr\u00e1ficos y de comportamiento.<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\"><b>Variedad de formatos y canales (v\u00eddeo, CTV, display, contextual, producto patrocinado)<\/b><\/td><td class=\"column-2\"><b>Si.<\/b> <br \/>\nTodas estas opciones son posibles con los Commerce Media.<\/td><td class=\"column-3\"><b>A veces. <\/b><br \/>\nLas plataformas de Retail Media que ofrecen anuncios offsite pueden incluir algunos de estos formatos, pero no suelen incluirlos todos.<\/td><td class=\"column-4\"><b>No.<\/b> <br \/>\nLos productos patrocinados no son una opci\u00f3n aqu\u00ed.<\/td><td class=\"column-5\"><b>No.<\/b> <br \/>\nLos productos patrocinados no son una opci\u00f3n aqu\u00ed.<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\"><b>Espacio publicitario en publishers en el Internet abierto<\/b><\/td><td class=\"column-2\"><b>Si.<\/b> <br \/>\nLos Commerce Media incluyen anuncios tanto en publishers como en retailers.<\/td><td class=\"column-3\"><b>A veces. <\/b><br \/>\nAlgunos proveedores de Retail Media ofrecen anuncios offsite.<\/td><td class=\"column-4\"><b>Si.<\/b><\/td><td class=\"column-5\"><b>Si.<\/b><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\"><b>Funciona para anunciantes que no est\u00e1n en el sector retail<\/b><\/td><td class=\"column-2\"><b>Si.<\/b> <br \/>\nLos Commerce Media funcionan para negocios retail y negocios que no son de retail, como Clasificados, Viajes y Finanzas.<\/td><td class=\"column-3\"><b>No.<\/b><br \/>\n El Retail Media est\u00e1 centrado en ayudar a las marcas a vender productos en retailers.<\/td><td class=\"column-4\"><b>Si.<\/b><\/td><td class=\"column-5\"><b>Si.<\/b><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\"><b>Supply y Demand (oferta y demanda) conectadas para la medici\u00f3n en bucle cerrado<\/b><\/td><td class=\"column-2\"><b>Si.<\/b> <br \/>\nLos Commerce Media conectan directamente a los Profesionales del Marketing y a los propietarios de medios.<\/td><td class=\"column-3\"><b>Si.<\/b><br \/>\nLos Commerce Media conectan directamente a los Profesionales del Marketing y a los propietarios de medios.<\/td><td class=\"column-4\"><b>No.<\/b><\/td><td class=\"column-5\"><b>No.<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<p>&nbsp;<\/p>\n"}]}]}},{"section_title":"\u00bfPor qu\u00e9 est\u00e1n en tendencia?","section_anchor":"why-is-it-trending","optional_section_classes":"","section_header_background_type":"image","section_header_background":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header-2-SPANISH-scaled.jpg","section_header_background_video":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header_2_notext.mp4","section_header_title_img":false,"section_body":{"content_area":[{"white_bg":true,"padded_left":false,"content":[{"acf_fc_layout":"image_with_description","image":{"ID":17796,"id":17796,"title":"retail_commerce_sales_worldwide-1-1","filename":"retail_commerce_sales_worldwide-1-1.svg","filesize":11615,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/retail_commerce_sales_worldwide-1-1\/","alt":"","author":"18","description":"","caption":"","name":"retail_commerce_sales_worldwide-1-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:40:02","modified":"2022-08-12 09:40:02","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":405,"height":466,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","thumbnail-width":405,"thumbnail-height":466,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","medium-width":405,"medium-height":466,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","medium_large-width":405,"medium_large-height":466,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","large-width":405,"large-height":466,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","1536x1536-width":405,"1536x1536-height":466,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","2048x2048-width":405,"2048x2048-height":466,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","success-story-width":405,"success-story-height":466,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","profile_24-width":405,"profile_24-height":466,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","profile_48-width":405,"profile_48-height":466,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","profile_96-width":405,"profile_96-height":466,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","profile_150-width":405,"profile_150-height":466,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/retail_commerce_sales_worldwide-1-1.svg","profile_300-width":405,"profile_300-height":466}},"description":"<p>Los Commerce Media est\u00e1n en tendencia, y estas son solo algunas de las razones:<\/p>\n<p><strong>El ecommerce sigue en auge, y a los consumidores sigue encant\u00e1ndoles ir a las tiendas f\u00edsicas:<\/strong> La pandemia del COVID-19 hizo que el mundo se conectara a internet para comprar, y sus nuevos h\u00e1bitos online continuar\u00e1n despu\u00e9s de la pandemia. Se prev\u00e9 que el ecommerce mundial se aproxime a los 7T\u00a0$ (m\u00e1s del doble de las ventas de 2019) y supondr\u00e1 casi un 25% de todas las ventas retail antes de 2025 (un aumento enorme si lo comparamos con la cuota del 13,8% que ten\u00eda en 2019).<sup>4<\/sup><\/p>\n"}]},{"white_bg":false,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>A su vez, nuestra investigaci\u00f3n muestra que cada vez son m\u00e1s los consumidores que utilizan opciones como BOPIS (compra online, recogida en tienda f\u00edsica) y \u00abClick and Collect\u00bb y que siguen valorando mucho la <a href=\"https:\/\/www.criteo.com\/es\/products\/omnichannel-retail\/\">la experiencia en persona de las tiendas f\u00edsicas<\/a>: a 4 de cada 10 consumidores no les gusta comprar art\u00edculos a menos que los puedan ver y tocar en tienda f\u00edsica.<sup>5<\/sup><\/p>\n"},{"acf_fc_layout":"image_with_mobile_version","desktop_version":{"ID":17797,"id":17797,"title":"how_much_do_you_agree-1-1","filename":"how_much_do_you_agree-1-1.svg","filesize":123208,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/how_much_do_you_agree-1-1\/","alt":"","author":"18","description":"","caption":"","name":"how_much_do_you_agree-1-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:40:37","modified":"2022-08-12 09:40:37","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":845,"height":351,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","thumbnail-width":845,"thumbnail-height":351,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","medium-width":845,"medium-height":351,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","medium_large-width":845,"medium_large-height":351,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","large-width":845,"large-height":351,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","1536x1536-width":845,"1536x1536-height":351,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","2048x2048-width":845,"2048x2048-height":351,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","success-story-width":845,"success-story-height":351,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","profile_24-width":845,"profile_24-height":351,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","profile_48-width":845,"profile_48-height":351,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","profile_96-width":845,"profile_96-height":351,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","profile_150-width":845,"profile_150-height":351,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_much_do_you_agree-1-1.svg","profile_300-width":845,"profile_300-height":351}},"mobile_version":{"ID":17760,"id":17760,"title":"Criteo_Commerce_Media_Guide_Graph-02-EN-mobile","filename":"Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","filesize":13526,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/criteo_commerce_media_guide_graph-02-en-mobile\/","alt":"","author":"18","description":"","caption":"","name":"criteo_commerce_media_guide_graph-02-en-mobile","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:02:37","modified":"2022-08-19 01:23:42","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":315,"height":885,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","thumbnail-width":315,"thumbnail-height":885,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","medium-width":315,"medium-height":885,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","medium_large-width":315,"medium_large-height":885,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","large-width":315,"large-height":885,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","1536x1536-width":315,"1536x1536-height":885,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","2048x2048-width":315,"2048x2048-height":885,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","success-story-width":315,"success-story-height":885,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","profile_24-width":315,"profile_24-height":885,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","profile_48-width":315,"profile_48-height":885,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","profile_96-width":315,"profile_96-height":885,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","profile_150-width":315,"profile_150-height":885,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-02-EN-mobile.svg","profile_300-width":315,"profile_300-height":885}}},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p><strong>La manera en la que podemos conectar con los consumidores cambia de manera continua:<\/strong> Las normativas sobre privacidad cada vez m\u00e1s restrictivas y la posible desaparici\u00f3n de cookies de terceros hacen que los Profesionales del Marketing y los propietarios de medios busquen nuevas formas de llegar a las audiencias de forma responsable y de monetizarlas.<\/p>\n"},{"acf_fc_layout":"image_with_mobile_version","desktop_version":{"ID":17863,"id":17863,"title":"ES - Criteo_Commerce_Media_Guide_Graph 03 EN - desktop (3)","filename":"ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","filesize":5356,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/es-criteo_commerce_media_guide_graph-03-en-desktop-3\/","alt":"","author":"55","description":"","caption":"","name":"es-criteo_commerce_media_guide_graph-03-en-desktop-3","status":"inherit","uploaded_to":17735,"date":"2022-08-26 14:29:31","modified":"2022-08-26 14:29:31","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":845,"height":296,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","thumbnail-width":845,"thumbnail-height":296,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","medium-width":845,"medium-height":296,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","medium_large-width":845,"medium_large-height":296,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","large-width":845,"large-height":296,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","1536x1536-width":845,"1536x1536-height":296,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","2048x2048-width":845,"2048x2048-height":296,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","success-story-width":845,"success-story-height":296,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","profile_24-width":845,"profile_24-height":296,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","profile_48-width":845,"profile_48-height":296,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","profile_96-width":845,"profile_96-height":296,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","profile_150-width":845,"profile_150-height":296,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ES-Criteo_Commerce_Media_Guide_Graph-03-EN-desktop-3.svg","profile_300-width":845,"profile_300-height":296}},"mobile_version":{"ID":17862,"id":17862,"title":"Es - Criteo_Commerce_Media_Guide_Graph 03 EN - mobile (5)","filename":"Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","filesize":15118,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/es-criteo_commerce_media_guide_graph-03-en-mobile-5\/","alt":"","author":"55","description":"","caption":"","name":"es-criteo_commerce_media_guide_graph-03-en-mobile-5","status":"inherit","uploaded_to":17735,"date":"2022-08-26 14:29:30","modified":"2022-08-26 14:29:30","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":315,"height":933,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","thumbnail-width":315,"thumbnail-height":933,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","medium-width":315,"medium-height":933,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","medium_large-width":315,"medium_large-height":933,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","large-width":315,"large-height":933,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","1536x1536-width":315,"1536x1536-height":933,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","2048x2048-width":315,"2048x2048-height":933,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","success-story-width":315,"success-story-height":933,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","profile_24-width":315,"profile_24-height":933,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","profile_48-width":315,"profile_48-height":933,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","profile_96-width":315,"profile_96-height":933,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","profile_150-width":315,"profile_150-height":933,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Es-Criteo_Commerce_Media_Guide_Graph-03-EN-mobile-5.svg","profile_300-width":315,"profile_300-height":933}}},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p><strong>En la actualidad priorizar las <\/strong><a href=\"https:\/\/www.criteo.com\/es\/blog\/what-is-the-first-party-media-network\/\"><strong>estrategias basadas en datos propios<\/strong><\/a><strong> es algo imprescindible para los publishers y retailers: <\/strong>Teniendo en cuenta el punto anterior, los Profesionales del Marketing se centran ahora en recopilar y ampliar los datos propios. Los publishers que est\u00e1n prepar\u00e1ndose para el descenso de los CPM por la p\u00e9rdida de cookies de terceros est\u00e1n ampliando sus estrategias de datos propios. Los retailers tambi\u00e9n est\u00e1n explorando m\u00e1s maneras de monetizar sus valiosos activos propios. Conectar a los Profesionales del Marketing con estos propietarios de medios es algo que beneficia a todas las partes.<\/p>\n"},{"acf_fc_layout":"blockquote","larger_quote":false,"pic":false,"quote":"\u00abLa oportunidad para nosotros en el ecosistema post-cookies de terceros es que somos propietarios de nuestros propios datos. Somos los \u00fanicos que conocemos y comprendemos a nuestros usuarios, que tienen una relaci\u00f3n recurrente basada en cookies propias\u00bb.","figcaption":"\u2014Stephanie Layser, Vicepresidente de Tecnolog\u00eda y Operaciones Publicitarias en News Corp.<sup>6<\/sup>"},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p><strong>El trade marketing est\u00e1 haciendo una transici\u00f3n hacia lo digital: <\/strong>Los presupuestos de las marcas siguen a sus consumidores online. El 92% de los anunciantes de marcas de la UE<sup>7<\/sup> y el 76% de los de EE. UU.<sup>8<\/sup> afirman que su crecimiento depende de la publicidad en Retail Media.<\/p>\n<p><strong>Los consumidores est\u00e1n confiando en el Internet abierto m\u00e1s que nunca: <\/strong>Los consumidores no solo compran en Amazon o buscan en Google. Nuestra investigaci\u00f3n muestra que m\u00e1s consumidores comienzan su b\u00fasqueda de productos en los sitios web de los retailers y de las marcas, que est\u00e1n superando a los marketplaces online y a los motores de b\u00fasqueda como el principal primer punto de contacto.<\/p>\n"},{"acf_fc_layout":"single_stat","stat":"66%","description":"Los consumidores pasan el 66% del tiempo en el Internet abierto<sup>9<\/sup>"},{"acf_fc_layout":"image_with_mobile_version","desktop_version":{"ID":17866,"id":17866,"title":"Criteo_Commerce_Media_Guide_Graph 04 EN - desktop","filename":"Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","filesize":7241,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/criteo_commerce_media_guide_graph-04-en-desktop\/","alt":"","author":"55","description":"","caption":"","name":"criteo_commerce_media_guide_graph-04-en-desktop","status":"inherit","uploaded_to":17735,"date":"2022-08-29 15:16:24","modified":"2022-08-29 15:16:24","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":845,"height":655,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","thumbnail-width":845,"thumbnail-height":655,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","medium-width":845,"medium-height":655,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","medium_large-width":845,"medium_large-height":655,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","large-width":845,"large-height":655,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","1536x1536-width":845,"1536x1536-height":655,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","2048x2048-width":845,"2048x2048-height":655,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","success-story-width":845,"success-story-height":655,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","profile_24-width":845,"profile_24-height":655,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","profile_48-width":845,"profile_48-height":655,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","profile_96-width":845,"profile_96-height":655,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","profile_150-width":845,"profile_150-height":655,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-desktop.svg","profile_300-width":845,"profile_300-height":655}},"mobile_version":{"ID":17764,"id":17764,"title":"Criteo_Commerce_Media_Guide_Graph-04-EN-mobile","filename":"Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","filesize":32621,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/criteo_commerce_media_guide_graph-04-en-mobile\/","alt":"","author":"18","description":"","caption":"","name":"criteo_commerce_media_guide_graph-04-en-mobile","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:02:45","modified":"2022-08-19 01:26:41","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":315,"height":1894,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","thumbnail-width":315,"thumbnail-height":1894,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","medium-width":315,"medium-height":1894,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","medium_large-width":315,"medium_large-height":1894,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","large-width":315,"large-height":1894,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","1536x1536-width":315,"1536x1536-height":1894,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","2048x2048-width":315,"2048x2048-height":1894,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","success-story-width":315,"success-story-height":1894,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","profile_24-width":315,"profile_24-height":1894,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","profile_48-width":315,"profile_48-height":1894,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","profile_96-width":315,"profile_96-height":1894,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","profile_150-width":315,"profile_150-height":1894,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Criteo_Commerce_Media_Guide_Graph-04-EN-mobile.svg","profile_300-width":315,"profile_300-height":1894}}},{"acf_fc_layout":"single_stat","stat":"7 de cada 10","description":"consumidores (68%) confirmaron que, antes de comprar productos que nunca hab\u00edan comprado online o productos importantes, leen con frecuencia art\u00edculos informativos en el Internet abierto.<sup>10<\/sup>"},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p><strong>Nuevas funciones de Directores comerciales est\u00e1n surgiendo en las agencias: <\/strong>Las personas que desempe\u00f1an estas nuevas funciones lideran con un enfoque 360\u00b0 del comercio, supervisando todo, desde la b\u00fasqueda y display, hasta el shopper marketing y el Retail Media. Sus objetivos son acabar con los silos y adoptar un enfoque basado en audiencias en lugar de un enfoque por canales o retailers.<\/p>\n"},{"acf_fc_layout":"single_stat","stat":"69%","description":"de los Profesionales del Marketing y los propietarios de medios afirmaron que la eliminaci\u00f3n de los silos por canales era una de sus principales prioridades para preparar sus acciones de marketing digital para el futuro<sup>1<\/sup>"}]}]}},{"section_title":"El ecosistema","section_anchor":"ecosystem","optional_section_classes":"pb-6","section_header_background_type":"image","section_header_background":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header-3-SPANISH-scaled.jpg","section_header_background_video":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header_3_notext.mp4","section_header_title_img":false,"section_body":{"content_area":[{"white_bg":true,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>El ecosistema de los Commerce Media se compone de 3 principales agentes: Profesionales del Marketing, Propietarios de medios y Consumidores. Cada uno tiene sus propios objetivos, retos y necesidades en los que iremos profundizando m\u00e1s adelante.<\/p>\n<h3>Profesionales del Marketing:<\/h3>\n<p>Las marcas, los retailers (m\u00e1s concretamente, los Profesionales de Marketing digital\/de marca\/crecimiento y los planificadores y compradores de medios entre ellos), y las agencias que los apoyan son el Demand Side del ecosistema de Commerce Media. Quieren activar campa\u00f1as publicitarias segmentadas que puedan llegar a los consumidores in-market desde el descubrimiento hasta la compra, centr\u00e1ndose en impulsar y medir los resultados en cada etapa.<\/p>\n"},{"acf_fc_layout":"media_slider","one_image_slider":true,"example_slider":false,"media_type":"image","single_image":{"ID":17800,"id":17800,"title":"ch3-a","filename":"ch3-a.png","filesize":48881,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/ch3-a\/","alt":"","author":"18","description":"","caption":"","name":"ch3-a","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:42:31","modified":"2022-08-12 09:42:31","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":360,"height":310,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-300x258.png","medium-width":300,"medium-height":258,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","medium_large-width":360,"medium_large-height":310,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","large-width":360,"large-height":310,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","1536x1536-width":360,"1536x1536-height":310,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","2048x2048-width":360,"2048x2048-height":310,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","success-story-width":360,"success-story-height":310,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-24x24.png","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-48x48.png","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-96x96.png","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-150x150.png","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-300x300.png","profile_300-width":300,"profile_300-height":300}},"single_wistia_video_id":"daajbaamp8","slides":[{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los Profesionales del Marketing necesitan: ","subtitle":"Datos comerciales e IA para entender mejor a los consumidores. ","description":"<p>El aprovechamiento del conjunto global de datos comerciales permite a los Profesionales del Marketing identificar patrones de inter\u00e9s e intenci\u00f3n de compra para enriquecer la segmentaci\u00f3n de audiencias y la personalizaci\u00f3n. Cuantos m\u00e1s datos comerciales puedan obtener los Profesionales del Marketing, m\u00e1s inteligentes ser\u00e1n sus campa\u00f1as.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los Profesionales del Marketing necesitan: ","subtitle":"Soluciones de publicidad basadas en datos propios.","description":"<p>Cuando Google cierre el grifo de las cookies de terceros, los datos propios ser\u00e1n una baza segura. Disponer de suficientes datos propios es un problema, especialmente en el sistema actual, en el que muchos pasos de coincidencia y sincronizaci\u00f3n pueden llevar a la p\u00e9rdida de datos. Los Profesionales del Marketing necesitar\u00e1n soluciones de Commerce Media que les ayuden a proteger y activar los datos propios con seguridad para la privacidad para cumplir los objetivos full-funnel.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los Profesionales del Marketing necesitan: ","subtitle":"Otras opciones aparte de los gigantes de Internet para lograr un mayor alcance y m\u00e1s control.","description":"<p>En una encuesta de Forrester Consulting que encargamos, el 80% de los norteamericanos<sup>8 <\/sup>\u00a0y el 77% de los encuestados europeos<sup>7<\/sup>\u00a0quer\u00edan reducir su dependencia de los gigantes digitales. Si a esto le a\u00f1adimos el hecho de que la mayor parte del ecommerce mundial se realiza fuera de Amazon, existe una necesidad imperiosa de Commerce Media en el Internet abierto.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los Profesionales del Marketing necesitan: ","subtitle":"La posibilidad de vincular la inversi\u00f3n en publicidad con los resultados.","description":"<p>Tanto si se trata del Brand Awareness, el tr\u00e1fico, los leads o las ventas, los Profesionales del Marketing deben poder medir el impacto de la publicidad digital a medida que los consumidores avanzan por el funnel.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los Profesionales del Marketing necesitan: ","subtitle":"El menor n\u00famero posible de plataformas para dinamizar la gesti\u00f3n.","description":"<p>Los Commerce Media en el Internet abierto son ineficientes y requieren el uso de m\u00faltiples plataformas, incluidas las Demand Side Platforms (DSP), Supply Side Platforms (SSP) y las plataformas de Retail Media.<\/p>\n"}]},{"acf_fc_layout":"wysiwyg","wysiwyg":"<h3>Propietarios de medios:<\/h3>\n<p>Los publishers, los retailers y los marketplaces son el margen de la oferta del ecosistema de los Commerce Media. Estos agentes quieren vender su inventario de publicidad y promociones a los Profesionales del Marketing.<\/p>\n"},{"acf_fc_layout":"media_slider","one_image_slider":true,"example_slider":false,"media_type":"image","single_image":{"ID":17801,"id":17801,"title":"ch3-b","filename":"ch3-b.png","filesize":28803,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b.png","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/ch3-b\/","alt":"","author":"18","description":"","caption":"","name":"ch3-b","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:43:02","modified":"2022-08-12 09:43:02","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":360,"height":310,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b-300x258.png","medium-width":300,"medium-height":258,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b.png","medium_large-width":360,"medium_large-height":310,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b.png","large-width":360,"large-height":310,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b.png","1536x1536-width":360,"1536x1536-height":310,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b.png","2048x2048-width":360,"2048x2048-height":310,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b.png","success-story-width":360,"success-story-height":310,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b-24x24.png","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b-48x48.png","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b-96x96.png","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b-150x150.png","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-b-300x300.png","profile_300-width":300,"profile_300-height":300}},"single_wistia_video_id":"perfvy74bg","slides":[{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los propietarios de medios necesitan:","subtitle":"Soluciones que les ayuden a monetizar sus audiencias y datos propios y a mejorar sus resultados.","description":"<p>Para la mayor\u00eda de los retailers, los requisitos tecnol\u00f3gicos necesarios para asumir con \u00e9xito el papel del publisher son demasiado complejos como para hacerlo por su cuenta. Del mismo modo, los publishers que quieren sacar m\u00e1s partido a su inventario necesitan datos comerciales externos y activos de IA que les ayuden a hacerlo.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los propietarios de medios necesitan:","subtitle":"Para poder captar m\u00e1s gasto de los anunciantes. ","description":"<p>Un ecosistema de Commerce Media aut\u00f3nomo puede simplificar el proceso y reducir las cuotas que se comen los beneficios de los propietarios de medios hoy en d\u00eda.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los propietarios de medios necesitan:","subtitle":"Soluciones para gestionar la recopilaci\u00f3n de datos propios, los derechos y la activaci\u00f3n. ","description":"<p>Para construir sus datos recopilados con permiso y seguros para la privacidad, los publishers necesitan soluciones de Commerce Media que les ayuden a educar a los consumidores, a lograr su consentimiento y a darles la posibilidad de gestionar sus preferencias.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los propietarios de medios necesitan:","subtitle":"Control.","description":"<p>Los propietarios de medios necesitan control sobre el acceso a los datos, sobre los precios y tambi\u00e9n sobre los contenidos para garantizar su relevancia.<\/p>\n"}]},{"acf_fc_layout":"wysiwyg","wysiwyg":"<h3>Consumidores<\/h3>\n<p>Los consumidores est\u00e1n en el centro del ecosistema. Es su deseo de mayor privacidad y control lo que est\u00e1 remodelando la industria publicitaria e informando a la naciente categor\u00eda de Commerce Media. Solo colaborando estrechamente podr\u00e1n, los Profesionales del Marketing y los propietarios de medios, ofrecer las experiencias que ganar\u00e1n la confianza y la lealtad de los consumidores en el futuro.<\/p>\n"},{"acf_fc_layout":"media_slider","one_image_slider":true,"example_slider":false,"media_type":"image","single_image":{"ID":17800,"id":17800,"title":"ch3-a","filename":"ch3-a.png","filesize":48881,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/ch3-a\/","alt":"","author":"18","description":"","caption":"","name":"ch3-a","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:42:31","modified":"2022-08-12 09:42:31","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":360,"height":310,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-300x258.png","medium-width":300,"medium-height":258,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","medium_large-width":360,"medium_large-height":310,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","large-width":360,"large-height":310,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","1536x1536-width":360,"1536x1536-height":310,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","2048x2048-width":360,"2048x2048-height":310,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a.png","success-story-width":360,"success-story-height":310,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-24x24.png","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-48x48.png","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-96x96.png","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-150x150.png","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch3-a-300x300.png","profile_300-width":300,"profile_300-height":300}},"single_wistia_video_id":"a5jkpjaiqe","slides":[{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los consumidores necesitan:","subtitle":"La capacidad de controlar el uso por parte de los Profesionales del Marketing y los propietarios de medios de aquellos datos que ellos consienten compartir. ","description":"<p>Los consumidores tienen que entender claramente el valor que tiene su consentimiento para el uso de sus datos y poder gestionar ese consentimiento para dar o rechazar su permiso en cualquier momento.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los consumidores necesitan:","subtitle":"Experiencias relevantes.","description":"<p>El llamamiento a un mayor control no significa que los consumidores dejen de estar interesados en experiencias relevantes. Los Profesionales del Marketing y los propietarios de medios que puedan satisfacer a los consumidores en un momento de deseo o necesidad, con el contenido adecuado, se ver\u00e1n recompensados con un mayor engagement.<\/p>\n"},{"media_type":"image","image":false,"wistia_video_id":"","uppercase_label":"Los consumidores necesitan:","subtitle":"Poder seguir accediendo a contenidos digitales de alta calidad, descubrir cosas nuevas y tener libertad de elecci\u00f3n.","description":"<p>La publicidad es lo que hace posible todo esto hoy en d\u00eda, ya que proporciona los fondos que los propietarios de medios necesitan para seguir ofreciendo contenidos y productos originales y diversos en el Internet abierto.<\/p>\n"}]}]}]}},{"section_title":"El estado actual","section_anchor":"current-state","optional_section_classes":"","section_header_background_type":"image","section_header_background":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header-4-SPANISH-scaled.jpg","section_header_background_video":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header_4_notext.mp4","section_header_title_img":false,"section_body":{"content_area":[{"white_bg":true,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>En la actualidad, muchos de los Commerce Media en el Internet abierto est\u00e1n fragmentados, con Demand Side Platforms (DSP), Supply Side Platforms (SSP) y plataformas de Retail Media, que operan por separado.<\/p>\n"},{"acf_fc_layout":"image_with_description","image":{"ID":17802,"id":17802,"title":"how_many_platforms-1-1-1","filename":"how_many_platforms-1-1-1.svg","filesize":4093,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/how_many_platforms-1-1-1\/","alt":"","author":"18","description":"","caption":"","name":"how_many_platforms-1-1-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:45:04","modified":"2022-08-12 09:45:04","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":441,"height":373,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","thumbnail-width":441,"thumbnail-height":373,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","medium-width":441,"medium-height":373,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","medium_large-width":441,"medium_large-height":373,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","large-width":441,"large-height":373,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","1536x1536-width":441,"1536x1536-height":373,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","2048x2048-width":441,"2048x2048-height":373,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","success-story-width":441,"success-story-height":373,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","profile_24-width":441,"profile_24-height":373,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","profile_48-width":441,"profile_48-height":373,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","profile_96-width":441,"profile_96-height":373,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","profile_150-width":441,"profile_150-height":373,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/how_many_platforms-1-1-1.svg","profile_300-width":441,"profile_300-height":373}},"description":"<p>De hecho, el estudio realizado por Forrester Consulting en nombre de Criteo revel\u00f3 que m\u00e1s del 40% de los Profesionales del Marketing utiliza entre <strong>6 y 10 plataformas diferentes<\/strong> para la compra de medios.<sup>1<\/sup><\/p>\n"}]},{"white_bg":false,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>Las soluciones de gesti\u00f3n de datos y segmentaci\u00f3n est\u00e1n en proceso de cambio, y surgen diferentes soluciones para hacer interoperables los datos seguros para la privacidad. Hay mucho que navegar, y los Profesionales del Marketing y los propietarios de medios est\u00e1n deseando encontrar soluciones seguras para la publicidad segmentable que sigan generando resultados. Tambi\u00e9n desean disponer de formas m\u00e1s din\u00e1micas de hacerlo, utilizando menos plataformas.<\/p>\n"},{"acf_fc_layout":"blockquote","larger_quote":false,"pic":{"ID":17773,"id":17773,"title":"pic_Megan_Clarken-1","filename":"pic_Megan_Clarken-1.svg","filesize":678627,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/pic_megan_clarken-1\/","alt":"","author":"18","description":"","caption":"","name":"pic_megan_clarken-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:03:04","modified":"2022-08-12 09:03:04","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":104,"height":104,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","thumbnail-width":104,"thumbnail-height":104,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","medium-width":104,"medium-height":104,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","medium_large-width":104,"medium_large-height":104,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","large-width":104,"large-height":104,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","1536x1536-width":104,"1536x1536-height":104,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","2048x2048-width":104,"2048x2048-height":104,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","success-story-width":104,"success-story-height":104,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","profile_24-width":104,"profile_24-height":104,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","profile_48-width":104,"profile_48-height":104,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","profile_96-width":104,"profile_96-height":104,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","profile_150-width":104,"profile_150-height":104,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","profile_300-width":104,"profile_300-height":104}},"quote":"\u201cTodo esto es realmente dif\u00edcil de entender para los Profesionales del Marketing: c\u00f3mo usar datos propios, c\u00f3mo encontrar nuevas audiencias, c\u00f3mo sortear la desaparici\u00f3n de las cookies de terceros. Y, por eso, est\u00e1n recurriendo a los proveedores de tecnolog\u00eda, como las empresas de tecnolog\u00eda publicitaria, para que les ayuden\u201d. ","figcaption":"\u2014 Megan Clarken, CEO, Criteo"}]},{"white_bg":true,"padded_left":false,"content":[{"acf_fc_layout":"single_stat","stat":"81%","description":"de los Profesionales del Marketing y los retailers (como propietarios de medios) dicen que una de las principales prioridades en los pr\u00f3ximos 12 meses ser\u00e1 implementar una plataforma \u00fanica para gestionar toda la inversi\u00f3n y los resultados obtenidos de los Commerce Media.<sup>1<\/sup>"}]},{"white_bg":false,"padded_left":false,"content":[{"acf_fc_layout":"image_with_description","image":{"ID":17803,"id":17803,"title":"organization_capabilities-1-1","filename":"organization_capabilities-1-1.svg","filesize":4262,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/organization_capabilities-1-1\/","alt":"","author":"18","description":"","caption":"","name":"organization_capabilities-1-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:45:28","modified":"2022-08-12 09:45:28","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":391,"height":333,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","thumbnail-width":391,"thumbnail-height":333,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","medium-width":391,"medium-height":333,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","medium_large-width":391,"medium_large-height":333,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","large-width":391,"large-height":333,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","1536x1536-width":391,"1536x1536-height":333,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","2048x2048-width":391,"2048x2048-height":333,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","success-story-width":391,"success-story-height":333,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","profile_24-width":391,"profile_24-height":333,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","profile_48-width":391,"profile_48-height":333,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","profile_96-width":391,"profile_96-height":333,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","profile_150-width":391,"profile_150-height":333,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/organization_capabilities-1-1.svg","profile_300-width":391,"profile_300-height":333}},"description":"<p>Los encuestados tambi\u00e9n buscan partners de Commerce Media que les ayuden a optimizar el rendimiento y mejorar el dinamismo. Cuando Forrester Consulting pregunt\u00f3 qu\u00e9 capacidades eran las m\u00e1s valiosas a la hora de seleccionar un socio comercial, el 63% dijo que la capacidad de comparar y optimizar el rendimiento en todos los canales y retailers y el 59% dijo que la capacidad de medir el rendimiento y ajustar la inversi\u00f3n de la campa\u00f1a en tiempo real. Casi la mitad (47%) de los encuestados tambi\u00e9n buscan socios que puedan proporcionar acceso a una gran cantidad de datos propios.<\/p>\n"},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>El espacio de los Commerce Media est\u00e1 avanzando r\u00e1pidamente para satisfacer estas necesidades, facilitando la colaboraci\u00f3n eficaz entre los Profesionales del Marketing y los propietarios de medios.<\/p>\n<p>El objetivo es conectarlos en un marketplace abierto a trav\u00e9s de una \u00fanica interfaz. En este marketplace, los datos pueden compartirse para relacionar las identidades, crear y escalar audiencias segmentadas, y activarlas a trav\u00e9s de una variedad de canales y formatos. La medici\u00f3n y la optimizaci\u00f3n ser\u00e1n posibles en todos los canales y retailers desde un \u00fanico lugar, para obtener una visi\u00f3n verdaderamente hol\u00edstica.<\/p>\n"},{"acf_fc_layout":"blockquote","larger_quote":false,"pic":{"ID":17775,"id":17775,"title":"pic_Todd_Parsons-1","filename":"pic_Todd_Parsons-1.svg","filesize":636981,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/pic_todd_parsons-1\/","alt":"","author":"18","description":"","caption":"","name":"pic_todd_parsons-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:03:06","modified":"2022-08-12 09:03:06","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":104,"height":104,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","thumbnail-width":104,"thumbnail-height":104,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","medium-width":104,"medium-height":104,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","medium_large-width":104,"medium_large-height":104,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","large-width":104,"large-height":104,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","1536x1536-width":104,"1536x1536-height":104,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","2048x2048-width":104,"2048x2048-height":104,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","success-story-width":104,"success-story-height":104,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","profile_24-width":104,"profile_24-height":104,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","profile_48-width":104,"profile_48-height":104,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","profile_96-width":104,"profile_96-height":104,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","profile_150-width":104,"profile_150-height":104,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Todd_Parsons-1.svg","profile_300-width":104,"profile_300-height":104}},"quote":"\u00abLas empresas que permitan a publishers y anunciantes proteger los derechos de los consumidores y, adem\u00e1s, conectar sus datos propios, tanto del extremo de compra como el de venta, ser\u00e1n las que definir\u00e1n el siguiente cap\u00edtulo de publicidad personalizada\u00bb. ","figcaption":"\u2014 Todd Parsons, Director de Productos de Criteo"},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>Cada agente obtiene lo que necesita para tener \u00e9xito, desde los datos hasta la tecnolog\u00eda y las conexiones, creando un sistema autosuficiente y un c\u00edrculo virtuoso en el que todos se benefician mutuamente:<\/p>\n"},{"acf_fc_layout":"three_columns","columns":[{"description":"<strong>Los Profesionales del Marketing<\/strong><br>logran un suficiente alcance de audiencia segmentable y resultados medibles para seguir realizando campa\u00f1as."},{"description":"<strong>Los propietarios de medios<\/strong><br>consiguen ingresos por publicidad para seguir desarrollando\/ mejorando los contenidos para atraer a las audiencias."},{"description":"<strong>Los consumidores<\/strong><br>disfrutan de una mejor experiencia por parte de los propietarios de medios y de los Profesionales del Marketing de confianza."}]}]}]}},{"section_title":"Por qu\u00e9 los necesitas ahora","section_anchor":"why-you-need-it-now","optional_section_classes":"","section_header_background_type":"image","section_header_background":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header-5-SPANISH-scaled.jpg","section_header_background_video":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header_5_notext.mp4","section_header_title_img":false,"section_body":{"content_area":[{"white_bg":true,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<h3>Prepara tu publicidad a prueba para el futuro.<\/h3>\n<p>Aspectos como la privacidad, las cookies, la capacidad de segmentaci\u00f3n y la medici\u00f3n de resultados tienen en vilo a todo el sector de la publicidad digital. En la actualidad hay m\u00e1s consumidores online que nunca, pero ofrecerles experiencias personalizadas es cada vez m\u00e1s dif\u00edcil. Los Commerce Media son una soluci\u00f3n para estos grandes cambios que est\u00e1n revolucionando el sector, porque provienen de datos propios. Los datos propios son el futuro de la publicidad digital porque ser\u00e1n clave para relacionar, de manera responsable, la identidad de los consumidores en todos los entornos y crear un alcance de audiencias segmentables.<\/p>\n<p>Los Profesionales del Marketing que quieran llegar a una audiencia lo suficientemente grande como para hacer frente a la desaparici\u00f3n gradual de las cookies de terceros tienen que empezar ahora a aumentar su acceso a datos propios. Los Commerce Media les ayudan a conseguirlo de 3 maneras:<\/p>\n"},{"acf_fc_layout":"ordered_stats","stat":[{"description":"Ampl\u00edan el alcance de los datos propios al enriquecerlos con una base de datos comerciales propios m\u00e1s grande, que puede utilizarse para crear nuevas audiencias."},{"description":"Aumentan la eficacia del targeting y de la personalizaci\u00f3n para atraer a audiencias de alta calidad con m\u00e1s probabilidades de consentir compartir sus datos, aumentando as\u00ed el conjunto de audiencias por las que podr\u00e1s segmentar."},{"description":"Reducen la p\u00e9rdida de datos que se produce por los numerosos pasos de relaci\u00f3n y sincronizaci\u00f3n que se producen en el sistema actual."}]},{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>En el caso de los publishers, que se enfrentan a lograr peores resultados cuando desaparezcan las cookies de terceros, los Retail Media pueden ayudarles a compensar la diferencia, proporcionando la tecnolog\u00eda y los datos que necesitan para convertir sus propios datos en una oferta m\u00e1s atractiva para los anunciantes.<\/p>\n<p>Para los retailers, los Retail Media les permiten monetizar sus datos y audiencias sin necesidad de invertir en la construcci\u00f3n de su propia Retail Media Platform. Tambi\u00e9n les ofrecen las herramientas que necesitan para atraer y generar conversi\u00f3n entre los consumidores. Esto significa que pueden hacer crecer su negocio publicitario y aumentar las ventas de productos desde un \u00fanico lugar centralizado.<\/p>\n<p>Tanto para los publishers como para los retailers, los Commerce Media ofrecen una mayor demanda por parte de quienes quieren llegar a las audiencias en el Internet abierto. Al relacionar los datos propios con la demanda y la oferta, tambi\u00e9n aumenta la capacidad de segmentaci\u00f3n, lo que se traduce en un mayor gasto por parte de los compradores.<\/p>\n"}]},{"white_bg":false,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<h3>Simplifica y cierra el c\u00edrculo<\/h3>\n<p>Los Commerce Media resuelven el problema de la fragmentaci\u00f3n, lo que permite a los Profesionales del Marketing y a los propietarios de medios simplificar el crecimiento y utilizar menos tecnolog\u00eda, en lugar de m\u00e1s.<\/p>\n<p>Al conectar directamente a los Profesionales del Marketing y a los propietarios de medios, los Commerce Media facilitan el seguimiento del impacto de las campa\u00f1as digitales en los KPI (como las ventas, los clientes potenciales, las visitas), tanto online como en tienda f\u00edsica. Esta capacidad de conectar la inversi\u00f3n en medios con los datos reales de compra presenta una publicidad que ofrece mediciones precisas de resultados a la que los Profesionales del Marketing estar\u00e1n deseando destinar sus presupuestos.<\/p>\n"},{"acf_fc_layout":"single_stat","stat":"6 de cada 10","description":"Profesionales del Marketing y retailers (como propietarios de medios) afirman que los principales beneficios de adoptar un enfoque centrado en Commerce Media son la mejora de la experiencia del consumidor (63%), el aumento del crecimiento (65%) y el aumento de la rentabilidad (61%)<sup>1<\/sup>"},{"acf_fc_layout":"boxes_with_stats","stats":[{"icon":{"ID":17778,"id":17778,"title":"chart-line-1","filename":"chart-line-1.svg","filesize":2052,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/chart-line-1\/","alt":"","author":"18","description":"","caption":"","name":"chart-line-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:03:11","modified":"2022-08-12 09:03:11","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":42,"height":42,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","thumbnail-width":42,"thumbnail-height":42,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","medium-width":42,"medium-height":42,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","medium_large-width":42,"medium_large-height":42,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","large-width":42,"large-height":42,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","1536x1536-width":42,"1536x1536-height":42,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","2048x2048-width":42,"2048x2048-height":42,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","success-story-width":42,"success-story-height":42,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","profile_24-width":42,"profile_24-height":42,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","profile_48-width":42,"profile_48-height":42,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","profile_96-width":42,"profile_96-height":42,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","profile_150-width":42,"profile_150-height":42,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/chart-line-1.svg","profile_300-width":42,"profile_300-height":42}},"stat":"65%","description":"Mayor crecimiento"},{"icon":{"ID":17779,"id":17779,"title":"smile-dizzy-1","filename":"smile-dizzy-1.svg","filesize":3503,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/smile-dizzy-1\/","alt":"","author":"18","description":"","caption":"","name":"smile-dizzy-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:03:12","modified":"2022-08-12 09:03:12","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":47,"height":47,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","thumbnail-width":47,"thumbnail-height":47,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","medium-width":47,"medium-height":47,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","medium_large-width":47,"medium_large-height":47,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","large-width":47,"large-height":47,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","1536x1536-width":47,"1536x1536-height":47,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","2048x2048-width":47,"2048x2048-height":47,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","success-story-width":47,"success-story-height":47,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","profile_24-width":47,"profile_24-height":47,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","profile_48-width":47,"profile_48-height":47,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","profile_96-width":47,"profile_96-height":47,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","profile_150-width":47,"profile_150-height":47,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/smile-dizzy-1.svg","profile_300-width":47,"profile_300-height":47}},"stat":"63%","description":"Mejor experiencia del cliente"},{"icon":{"ID":17780,"id":17780,"title":"presentation-line-1","filename":"presentation-line-1.svg","filesize":3700,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/presentation-line-1\/","alt":"","author":"18","description":"","caption":"","name":"presentation-line-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:03:13","modified":"2022-08-12 09:03:13","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":42,"height":42,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","thumbnail-width":42,"thumbnail-height":42,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","medium-width":42,"medium-height":42,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","medium_large-width":42,"medium_large-height":42,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","large-width":42,"large-height":42,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","1536x1536-width":42,"1536x1536-height":42,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","2048x2048-width":42,"2048x2048-height":42,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","success-story-width":42,"success-story-height":42,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","profile_24-width":42,"profile_24-height":42,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","profile_48-width":42,"profile_48-height":42,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","profile_96-width":42,"profile_96-height":42,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","profile_150-width":42,"profile_150-height":42,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/presentation-line-1.svg","profile_300-width":42,"profile_300-height":42}},"stat":"61%","description":"Mayor rentabilidad"}]},{"acf_fc_layout":"wysiwyg","wysiwyg":"<h3>Sit\u00faa a los consumidores en el centro de todo.<\/h3>\n<p>Los consumidores quieren saber que se est\u00e1n protegiendo sus datos. Pero esto no significa que los consumidores dejen de estar interesados en experiencias relevantes. Los Commerce Media impulsan una publicidad responsable <em>y<\/em> relevante. Debido a su enfoque centrado en la audiencia, los Commerce Media se construyen para atender a las necesidades de los consumidores y evolucionan a medida que estas lo hacen.<\/p>\n<p>Los consumidores tambi\u00e9n quieren poder acceder a una variedad de contenidos, productos y servicios. Gracias a los Commerce Media, los Profesionales del Marketing y los propietarios de Commerce Media impulsan una publicidad que apoya la diversidad y la capacidad de elecci\u00f3n en el Internet abierto.<\/p>\n<h3>Disfruta de control, transparencia y equilibrio.<\/h3>\n<p>A medida que los gigantes digitales se van cerrando m\u00e1s sobre s\u00ed mismos son fundamentales unas opciones que preserven el acceso y el control de los Profesionales del Marketing de sus datos propios. Los Commerce Media est\u00e1n en el Internet abierto, donde todos los agentes tienen la libertad de acceder y conservar sus datos, recurrir a los socios que deseen, fijar los precios y mantener el control sobre la experiencia del consumidor. Es una forma de reducir la dependencia de los gigantes digitales y construir una estrategia m\u00e1s equilibrada que se adapte a los consumidores en todos los lugares en los que pasan su tiempo, y en la que no haya muros que impidan ver el proceso de compra del cliente.<\/p>\n"},{"acf_fc_layout":"blockquote","larger_quote":false,"pic":false,"quote":"\u201cConstruir, establecer y mantener una relaci\u00f3n con los clientes (no solo para una \u00fanica conversi\u00f3n, sino a lo largo de su vida con una marca) es cada vez m\u00e1s importante para todos los Profesionales del Marketing actuales con los que he trabajado. Cuando una marca entienda al cliente y cada parte de su proceso de compra y disponga de todos los datos vinculados, los gigantes digitales dejar\u00e1n de tener una raz\u00f3n de ser.\u201d<sup>11<\/sup>","figcaption":"\u2014 Director general de estrategia, Publicis Media"},{"acf_fc_layout":"wysiwyg","wysiwyg":"<h3>Ventajas de los Commerce Media:<\/h3>\n\n<table id=\"tablepress-2\" class=\"tablepress tablepress-id-2 tablepress-responsive tablepress-responsive-phone\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><b>Profesionales del Marketing<\/b><\/th><th class=\"column-2\"><b>Propietarios de medios<\/b><\/th><th class=\"column-3\"><b>Consumidores<\/b><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Logran una capacidad de segmentaci\u00f3n escalable, con audiencias y personalizaci\u00f3n impulsadas por datos propios. <\/td><td class=\"column-2\">Consiguen m\u00e1s ingresos publicitarios mediante la monetizaci\u00f3n de los datos propios y las audiencias.<\/td><td class=\"column-3\">Sirven \u00fanicamente anuncios para los art\u00edculos en los que han mostrado activamente inter\u00e9s los consumidores, y solo de aquellos anunciantes a los que han dado su consentimiento.<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Invierten mejor el dinero y aumentan el engagement y la conversi\u00f3n centr\u00e1ndose en las audiencias in-market y aprovechando los insights comerciales detallados.<\/td><td class=\"column-2\">Aumentan el n\u00famero de visitantes recurrentes y las ventas utilizando los datos comerciales para personalizar el contenido oportuno para cada usuario.<\/td><td class=\"column-3\">Experiencias en sitio web y anuncios m\u00e1s relevantes.<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Reducen el n\u00famero de plataformas que se utilizan.<\/td><td class=\"column-2\">Aumentan la capacidad de segmentaci\u00f3n del inventario mediante la conexi\u00f3n de datos propios a lo largo de todo el ecosistema. <\/td><td class=\"column-3\">Promueven la diversidad de contenido y las opciones que ofrece el Internet abierto.<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Llegan a los consumidores en el Internet abierto, donde pasan el 66% de su tiempo, y donde los Profesionales del Marketing tienen pleno control y transparencia.<\/td><td class=\"column-2\">Conectan directamente con los Profesionales del Marketing que buscan audiencias segmentables y mantienen el control del acceso a los datos, los precios y la experiencia en el sitio web.<\/td><td class=\"column-3\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n"}]}]}},{"section_title":"Commerce Media Platform","section_anchor":"commerce-media-platform","optional_section_classes":"","section_header_background_type":"image","section_header_background":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header-6-SPANISH-scaled.jpg","section_header_background_video":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/Header_6_notext.mp4","section_header_title_img":false,"section_body":{"content_area":[{"white_bg":true,"padded_left":false,"content":[{"acf_fc_layout":"wysiwyg","wysiwyg":"<p>Criteo est\u00e1 utilizando su acceso a datos propios para construir un marketplace abierto para los Profesionales del Marketing y los propietarios de medios que permitir\u00e1 una segmentaci\u00f3n responsable de Commerce Media para el futuro. Somos una de las pocas plataformas con un n\u00famero importante de activos en ambos extremos del ecosistema, que nos permite ofrecer estas conexiones y operar a gran escala.<\/p>\n<p>La <a href=\"https:\/\/www.criteo.com\/es\/commerce-media-platform\/\">Criteo Commerce Media Platform\u00a0<\/a>permite a los Profesionales del Marketing y a los propietarios de medios convertir la mayor base de datos comerciales abierta del mundo en publicidad segmentable de alto rendimiento en el Internet abierto. Con nuestra First-Party Media Network y la IA centrada en el comercio, podemos ofrecer audiencias \u00fanicas y muy eficaces (junto con las herramientas para activarlas) para brindar experiencias m\u00e1s ricas a los consumidores en el Internet abierto.<\/p>\n"},{"acf_fc_layout":"media_slider","one_image_slider":false,"example_slider":false,"media_type":"image","single_image":false,"single_wistia_video_id":"","slides":[{"media_type":"image","image":{"ID":17804,"id":17804,"title":"ch6-a","filename":"ch6-a.png","filesize":12435,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a.png","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/ch6-a\/","alt":"","author":"18","description":"","caption":"","name":"ch6-a","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:46:14","modified":"2022-08-12 09:46:14","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":351,"height":310,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a-300x265.png","medium-width":300,"medium-height":265,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a.png","medium_large-width":351,"medium_large-height":310,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a.png","large-width":351,"large-height":310,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a.png","1536x1536-width":351,"1536x1536-height":310,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a.png","2048x2048-width":351,"2048x2048-height":310,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a.png","success-story-width":351,"success-story-height":310,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a-24x24.png","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a-48x48.png","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a-96x96.png","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a-150x150.png","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-a-300x300.png","profile_300-width":300,"profile_300-height":300}},"wistia_video_id":"p1poirxch0","uppercase_label":"","subtitle":"","description":"<h4>Supply y Demand en un \u00fanico punto centralizado<\/h4>\n<p>Benef\u00edciate de m\u00e1s datos y transparencia y menos costes con una plataforma unificada tanto para Profesionales del Marketing como para propietarios de medios.<\/p>\n<ul>\n<li>Logra reducir la p\u00e9rdida de datos, las cuotas y las tasas tecnol\u00f3gicas<\/li>\n<li>Aumenta tu capacidad de segmentaci\u00f3n<\/li>\n<li>Disfruta de acceso exclusivo al inventario in situ de Retail Media<\/li>\n<li>Aumenta el ROI y los ingresos<\/li>\n<\/ul>\n"},{"media_type":"image","image":{"ID":17805,"id":17805,"title":"ch6-b","filename":"ch6-b.png","filesize":11784,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b.png","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/ch6-b\/","alt":"","author":"18","description":"","caption":"","name":"ch6-b","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:46:39","modified":"2022-08-12 09:46:39","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":351,"height":310,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b-300x265.png","medium-width":300,"medium-height":265,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b.png","medium_large-width":351,"medium_large-height":310,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b.png","large-width":351,"large-height":310,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b.png","1536x1536-width":351,"1536x1536-height":310,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b.png","2048x2048-width":351,"2048x2048-height":310,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b.png","success-story-width":351,"success-story-height":310,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b-24x24.png","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b-48x48.png","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b-96x96.png","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b-150x150.png","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-b-300x300.png","profile_300-width":300,"profile_300-height":300}},"wistia_video_id":"16hq0adnaz","uppercase_label":"","subtitle":"","description":"<h4>First-Party Media Network<\/h4>\n<p>Logra una mayor capacidad de segmentaci\u00f3n conectando tus datos propios con nuestra red de datos propios de alta calidad.<\/p>\n<ul>\n<li>Vincula la identidad de los participantes para escalar audiencias<\/li>\n<li>Accede a datos comerciales para mejorar la personalizaci\u00f3n<\/li>\n<li>Garantiza la seguridad de los datos de los consumidores y el cumplimiento de las normativas de privacidad<\/li>\n<\/ul>\n"},{"media_type":"image","image":{"ID":17806,"id":17806,"title":"ch6-c","filename":"ch6-c.png","filesize":12509,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c.png","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/ch6-c\/","alt":"","author":"18","description":"","caption":"","name":"ch6-c","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:47:04","modified":"2022-08-12 09:47:04","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":351,"height":310,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c-300x265.png","medium-width":300,"medium-height":265,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c.png","medium_large-width":351,"medium_large-height":310,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c.png","large-width":351,"large-height":310,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c.png","1536x1536-width":351,"1536x1536-height":310,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c.png","2048x2048-width":351,"2048x2048-height":310,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c.png","success-story-width":351,"success-story-height":310,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c-24x24.png","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c-48x48.png","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c-96x96.png","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c-150x150.png","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-c-300x300.png","profile_300-width":300,"profile_300-height":300}},"wistia_video_id":"s2g3f5je0b","uppercase_label":"","subtitle":"","description":"<h4>Audiencias exclusivas basadas en la intenci\u00f3n de compra<\/h4>\n<p>Dir\u00edgete a audiencias muy efectivas y segm\u00e9ntalas a partir de una base de datos comerciales mundial masiva, unida a tus datos propios.<\/p>\n<ul>\n<li>C\u00e9ntrate en los consumidores in-market<\/li>\n<li>Genera primeras compras y compras recurrentes<\/li>\n<li>Atrae a anunciantes con nuevas audiencias<\/li>\n<\/ul>\n"},{"media_type":"image","image":{"ID":17807,"id":17807,"title":"ch6-d","filename":"ch6-d.png","filesize":10382,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d.png","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/ch6-d\/","alt":"","author":"18","description":"","caption":"","name":"ch6-d","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:47:34","modified":"2022-08-12 09:47:34","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":351,"height":310,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d-300x265.png","medium-width":300,"medium-height":265,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d.png","medium_large-width":351,"medium_large-height":310,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d.png","large-width":351,"large-height":310,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d.png","1536x1536-width":351,"1536x1536-height":310,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d.png","2048x2048-width":351,"2048x2048-height":310,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d.png","success-story-width":351,"success-story-height":310,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d-24x24.png","profile_24-width":24,"profile_24-height":24,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d-48x48.png","profile_48-width":48,"profile_48-height":48,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d-96x96.png","profile_96-width":96,"profile_96-height":96,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d-150x150.png","profile_150-width":150,"profile_150-height":150,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/ch6-d-300x300.png","profile_300-width":300,"profile_300-height":300}},"wistia_video_id":"joktp99e72","uppercase_label":"","subtitle":"","description":"<h4>Una soluci\u00f3n integral<\/h4>\n<p>Planifica, compra, personaliza, mide y monetiza, todo desde una \u00fanica plataforma.<\/p>\n<ul>\n<li>Escoge de una amplia variedad de audiencias, formatos de anuncios y opciones de compra de medios<\/li>\n<li>Mide y optimiza campa\u00f1as a lo largo del embudo de ventas<\/li>\n<li>Controla en todo momento tu inventario y todos tus datos<\/li>\n<\/ul>\n"}]}]},{"white_bg":false,"padded_left":false,"content":[{"acf_fc_layout":"blockquote","larger_quote":true,"pic":{"ID":17773,"id":17773,"title":"pic_Megan_Clarken-1","filename":"pic_Megan_Clarken-1.svg","filesize":678627,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","link":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/pic_megan_clarken-1\/","alt":"","author":"18","description":"","caption":"","name":"pic_megan_clarken-1","status":"inherit","uploaded_to":17735,"date":"2022-08-12 09:03:04","modified":"2022-08-12 09:03:04","menu_order":0,"mime_type":"image\/svg+xml","type":"image","subtype":"svg+xml","icon":"https:\/\/www.criteo.com\/es\/wp-includes\/images\/media\/default.png","width":104,"height":104,"sizes":{"thumbnail":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","thumbnail-width":104,"thumbnail-height":104,"medium":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","medium-width":104,"medium-height":104,"medium_large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","medium_large-width":104,"medium_large-height":104,"large":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","large-width":104,"large-height":104,"1536x1536":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","1536x1536-width":104,"1536x1536-height":104,"2048x2048":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","2048x2048-width":104,"2048x2048-height":104,"success-story":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","success-story-width":104,"success-story-height":104,"profile_24":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","profile_24-width":104,"profile_24-height":104,"profile_48":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","profile_48-width":104,"profile_48-height":104,"profile_96":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","profile_96-width":104,"profile_96-height":104,"profile_150":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","profile_150-width":104,"profile_150-height":104,"profile_300":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/pic_Megan_Clarken-1.svg","profile_300-width":104,"profile_300-height":104}},"quote":"\u201cEn el futuro, me gustar\u00eda poder decir que el Internet abierto est\u00e1 vivo y activo. Y que los consumidores lo adoran por la contribuci\u00f3n que ha realizado Criteo. Donde los nuevos negocios puedan llegar y prosperar, la innovaci\u00f3n pueda ocupar un lugar central y la publicidad pueda pagar m\u00e1s y m\u00e1s experiencias en el Internet abierto. Un entorno realmente vibrante para todos: esa es nuestra promesa\u201d. ","figcaption":"\u2014 Megan Clarken, Directora General de Criteo"}]}]}}],"footer_title":"Fuentes","sources":"<p><sup>1<\/sup>\u00a0Fuente: Un estudio encargado por Forrester Consulting en nombre de Criteo, septiembre de 2021<\/p>\n<p><sup>2<\/sup>\u00a0Fuente: Criteo Shopper Story, Global (Australia, Francia, Alemania, Jap\u00f3n, Corea del Sur, Reino Unido, Estados Unidos), agosto-noviembre 2021, N=6794 \/ julio-octubre 2019, N=6346.<\/p>\n<p><sup>3<\/sup>\u00a0Fuente: Criteo Shopper Story, Global (Australia, Francia, Alemania, Jap\u00f3n, Corea del Sur, Reino Unido, Estados Unidos), agosto-noviembre 2021, N=7282 \/ julio-octubre 2019, N=7102.<\/p>\n<p><sup>4 <\/sup>Fuente: <a href=\"https:\/\/www.emarketer.com\/content\/worldwide-ecommerce-continues-double-digit-growth-following-pandemic-push-online\">https:\/\/www.emarketer.com\/content\/worldwide-ecommerce-continues-double-digit-growth-following-pandemic-push-online<\/a><\/p>\n<p><sup>5<\/sup>\u00a0Fuente: Criteo Shopper Story, Global (Australia, Francia, Alemania, Jap\u00f3n, Corea del Sur, Reino Unido, Estados Unidos), agosto-noviembre 2021, N=6794 \/ julio-octubre 2019, N=6346.<\/p>\n<p><sup>6<\/sup>\u00a0Fuente: \u201cPublisher Ad Monetization After the Third-Party Cookie\u201d, Insider Intelligence\/eMarketer, Audrey Schomer, marzo de 2021<\/p>\n<p><sup>7\u00a0<\/sup>Fuente: Un estudio encargado por Forrester Consulting en nombre de Criteo, agosto de 2020. Base: 109 responsables europeos de publicidad tradicional o digital y\/o en tienda f\u00edsica, shopper marketing, trade marketing<\/p>\n<p><sup>8\u00a0<\/sup>Fuente: Un estudio encargado por Forrester Consulting en nombre de Criteo, julio de 2020. Base: 115 responsables norteamericanos de publicidad tradicional o digital y\/o en tienda f\u00edsica, shopper marketing y trade marketing<\/p>\n","additional_code":"","bevel":"peach-grapes","bevel_reversed":false,"side_text":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The Ultimate Guide to Commerce Media | ES - Criteo<\/title>\n<meta name=\"description\" content=\"Get up to speed on all things commerce media, including what it is, why it&#039;s trending, who&#039;s a part of the ecosystem, and much more.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Ultimate Guide to Commerce Media | ES - Criteo\" \/>\n<meta property=\"og:description\" content=\"Get up to speed on all things commerce media, including what it is, why it&#039;s trending, who&#039;s a part of the ecosystem, and much more.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/\" \/>\n<meta property=\"og:site_name\" content=\"ES - Criteo\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-03T15:48:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/The-Ultimate-Guide-to-Commerce-Media.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1441\" \/>\n\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\/\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/\",\n\t            \"url\": \"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/\",\n\t            \"name\": \"The Ultimate Guide to Commerce Media | ES - Criteo\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\/\/www.criteo.com\/es\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/The-Ultimate-Guide-to-Commerce-Media.png\",\n\t            \"datePublished\": \"2022-08-12T09:36:20+00:00\",\n\t            \"dateModified\": \"2024-04-03T15:48:29+00:00\",\n\t            \"description\": \"Get up to speed on all things commerce media, including what it is, why it's trending, who's a part of the ecosystem, and much more.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es-ES\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"es-ES\",\n\t            \"@id\": \"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/#primaryimage\",\n\t            \"url\": \"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/The-Ultimate-Guide-to-Commerce-Media.png\",\n\t            \"contentUrl\": \"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/The-Ultimate-Guide-to-Commerce-Media.png\",\n\t            \"width\": 1441,\n\t            \"height\": 699,\n\t            \"caption\": \"The Ultimate Guide to Commerce Media\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\/\/www.criteo.com\/es\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"The Ultimate Guide to Commerce Media\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\/\/www.criteo.com\/es\/#website\",\n\t            \"url\": \"https:\/\/www.criteo.com\/es\/\",\n\t            \"name\": \"ES - Criteo\",\n\t            \"description\": \"\",\n\t            \"publisher\": {\n\t                \"@id\": \"https:\/\/www.criteo.com\/es\/#organization\"\n\t            },\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\/\/www.criteo.com\/es\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es-ES\"\n\t        },\n\t        {\n\t            \"@type\": \"Organization\",\n\t            \"@id\": \"https:\/\/www.criteo.com\/es\/#organization\",\n\t            \"name\": \"Criteo\",\n\t            \"alternateName\": \"Criteo corp\",\n\t            \"url\": \"https:\/\/www.criteo.com\/es\/\",\n\t            \"logo\": {\n\t                \"@type\": \"ImageObject\",\n\t                \"inLanguage\": \"es-ES\",\n\t                \"@id\": \"https:\/\/www.criteo.com\/es\/#\/schema\/logo\/image\/\",\n\t                \"url\": \"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2024\/02\/Criteo-Logo.svg\",\n\t                \"contentUrl\": \"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2024\/02\/Criteo-Logo.svg\",\n\t                \"width\": 118,\n\t                \"height\": 24,\n\t                \"caption\": \"Criteo\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\/\/www.criteo.com\/es\/#\/schema\/logo\/image\/\"\n\t            }\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Ultimate Guide to Commerce Media | ES - Criteo","description":"Get up to speed on all things commerce media, including what it is, why it's trending, who's a part of the ecosystem, and much more.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/","og_locale":"es_ES","og_type":"article","og_title":"The Ultimate Guide to Commerce Media | ES - Criteo","og_description":"Get up to speed on all things commerce media, including what it is, why it's trending, who's a part of the ecosystem, and much more.","og_url":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/","og_site_name":"ES - Criteo","article_modified_time":"2024-04-03T15:48:29+00:00","og_image":[{"width":1441,"height":699,"url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/The-Ultimate-Guide-to-Commerce-Media.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/","url":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/","name":"The Ultimate Guide to Commerce Media | ES - Criteo","isPartOf":{"@id":"https:\/\/www.criteo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/#primaryimage"},"image":{"@id":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/The-Ultimate-Guide-to-Commerce-Media.png","datePublished":"2022-08-12T09:36:20+00:00","dateModified":"2024-04-03T15:48:29+00:00","description":"Get up to speed on all things commerce media, including what it is, why it's trending, who's a part of the ecosystem, and much more.","breadcrumb":{"@id":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/#primaryimage","url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/The-Ultimate-Guide-to-Commerce-Media.png","contentUrl":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2022\/08\/The-Ultimate-Guide-to-Commerce-Media.png","width":1441,"height":699,"caption":"The Ultimate Guide to Commerce Media"},{"@type":"BreadcrumbList","@id":"https:\/\/www.criteo.com\/es\/ultimate-guide-commerce-media\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.criteo.com\/es\/"},{"@type":"ListItem","position":2,"name":"The Ultimate Guide to Commerce Media"}]},{"@type":"WebSite","@id":"https:\/\/www.criteo.com\/es\/#website","url":"https:\/\/www.criteo.com\/es\/","name":"ES - Criteo","description":"","publisher":{"@id":"https:\/\/www.criteo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.criteo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.criteo.com\/es\/#organization","name":"Criteo","alternateName":"Criteo corp","url":"https:\/\/www.criteo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.criteo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2024\/02\/Criteo-Logo.svg","contentUrl":"https:\/\/www.criteo.com\/es\/wp-content\/uploads\/sites\/8\/2024\/02\/Criteo-Logo.svg","width":118,"height":24,"caption":"Criteo"},"image":{"@id":"https:\/\/www.criteo.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.criteo.com\/es\/wp-json\/wp\/v2\/pages\/17735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.criteo.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.criteo.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.criteo.com\/es\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.criteo.com\/es\/wp-json\/wp\/v2\/comments?post=17735"}],"version-history":[{"count":18,"href":"https:\/\/www.criteo.com\/es\/wp-json\/wp\/v2\/pages\/17735\/revisions"}],"predecessor-version":[{"id":19112,"href":"https:\/\/www.criteo.com\/es\/wp-json\/wp\/v2\/pages\/17735\/revisions\/19112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.criteo.com\/es\/wp-json\/wp\/v2\/media\/17736"}],"wp:attachment":[{"href":"https:\/\/www.criteo.com\/es\/wp-json\/wp\/v2\/media?parent=17735"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.criteo.com\/es\/wp-json\/wp\/v2\/coauthors?post=17735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}